{"id":3605,"date":"2022-11-27T14:10:02","date_gmt":"2022-11-27T14:10:02","guid":{"rendered":"https:\/\/cabowork.com\/?p=3605"},"modified":"2022-11-27T14:12:24","modified_gmt":"2022-11-27T15:12:24","slug":"unitek-innovation-lab-apresentada-ilha-do-sal","status":"publish","type":"post","link":"https:\/\/cabowork.com\/pt-pt\/unitek-innovation-lab-apresentada-ilha-do-sal\/","title":{"rendered":"Unitek Innovation Labs apresentada na ilha do Sal"},"content":{"rendered":"<p class=\"p2\">A<strong> Unitek<\/strong> <b>Innovation Labs<\/b> foi criada para ser uma \u201c<i>f\u00e1brica privada de inova\u00e7\u00e3o e desenvolvimento de softwares que tragam solu\u00e7\u00f5es que possam ajudar a acelerar as estrat\u00e9gias e a implementa\u00e7\u00e3o de medidas para o desenvolvimento do pa\u00eds<\/i>\u201d.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"p2\">Segundo a dire\u00e7\u00e3o da operadora m\u00f3vel, este laborat\u00f3rio funcionar\u00e1 com forte participa\u00e7\u00e3o de <a href=\"https:\/\/cabowork.com\/pt-pt\/jovens-empreendedorismo-cabo-verde-pro-empresa\/\" target=\"_blank\" rel=\"noopener\">jovens empreendedores e empreendedoras nacionais<\/a>, providenciando apoio e incuba\u00e7\u00e3o \u00e0s start ups ligadas ao desenvolvimento tecnol\u00f3gico e \u00e0 inova\u00e7\u00e3o.<\/p>\n<p class=\"p2\"><i>\u201cTrata-se de um ecossistema de inova\u00e7\u00e3o focado em acelerar processos ou projetos de inova\u00e7\u00e3o que ajudem \u00e0 transforma\u00e7\u00e3o e a toda a digitaliza\u00e7\u00e3o da sociedade cabo-verdiana\u201d<\/i>, disse em entrevista o <strong>Diretor Geral da UnitelT+, Inoweze Ferreira<\/strong>.<\/p>\n<h2><strong>Unitek Innovation Labs numa paisagem em permanente muta\u00e7\u00e3o.<\/strong><\/h2>\n<p class=\"p2\">Com o mundo <i>\u201ca mudar a uma velocidade vertiginosa\u201d<\/i>, a tecnologia e a internet assumem pap\u00e9is cada vez mais centrais <i>\u201cem todas as dimens\u00f5es pessoais e profissionais\u201d<\/i>. <i>\u201cA Pandemia acelerou ainda mais a digitaliza\u00e7\u00e3o das sociedades\u201d<\/i>, defendeu o respons\u00e1vel da Unitel T+.<\/p>\n<figure id=\"attachment_3597\" aria-describedby=\"caption-attachment-3597\" style=\"width: 800px\" class=\"wp-caption alignnone\"><img decoding=\"async\" class=\"size-large wp-image-3597\" src=\"https:\/\/cabowork.com\/wp-content\/uploads\/2022\/11\/Unitek-Ideas-Made-Real-1024x568.jpeg\" alt=\"Unitek Innovation Labs Capa do Facebook Oficial\" width=\"800\" height=\"444\" srcset=\"https:\/\/cabowork.com\/wp-content\/uploads\/2022\/11\/Unitek-Ideas-Made-Real-1024x568.jpeg 1024w, https:\/\/cabowork.com\/wp-content\/uploads\/2022\/11\/Unitek-Ideas-Made-Real-300x166.jpeg 300w, https:\/\/cabowork.com\/wp-content\/uploads\/2022\/11\/Unitek-Ideas-Made-Real-768x426.jpeg 768w, https:\/\/cabowork.com\/wp-content\/uploads\/2022\/11\/Unitek-Ideas-Made-Real-1536x852.jpeg 1536w, https:\/\/cabowork.com\/wp-content\/uploads\/2022\/11\/Unitek-Ideas-Made-Real.jpeg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-3597\" class=\"wp-caption-text\">Unitek Innovation Labs &#8211; Imagem promocional oficial |\u00a9 Unitel<\/figcaption><\/figure>\n<p class=\"p2\">Nas palavras de Inoweze Ferreira, <strong>o neg\u00f3cio tradicional das operadoras de telecomunica\u00e7\u00f5es est\u00e1 a mudar<\/strong>, transitando<i> \u201cde um modelo de neg\u00f3cios sustentado em servi\u00e7os de voz e dados para um modelo onde os servi\u00e7os e os conte\u00fados passam a desempenhar uma import\u00e2ncia fundamental na estrutura de receitas\u201d<\/i>. A diversifica\u00e7\u00e3o do portf\u00f3lio, aponta Ferreira, <i>\u201c\u00e9 a evolu\u00e7\u00e3o natural das operadoras que decidirem contribuir para o desenvolvimento das Na\u00e7\u00f5es\u201d<\/i>.<\/p>\n<p class=\"p2\">As solu\u00e7\u00f5es sa\u00eddas dos <a href=\"https:\/\/m.facebook.com\/unitek.cv\/\" target=\"_blank\" rel=\"noopener\">laborat\u00f3rios de inova\u00e7\u00e3o Unitek<\/a> que realmente tenham potencial para apoiar o desenvolvimento do pa\u00eds ser\u00e3o refor\u00e7adas com capacita\u00e7\u00e3o, orienta\u00e7\u00e3o, mentoria e investimento financeiro, por parte desta institui\u00e7\u00e3o e tamb\u00e9m dos seus parceiros p\u00fablicos e privados, de forma a facilitar a sua entrada no mercado e o sucesso dos neg\u00f3cios.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Unitek Innovation Labs foi criada para ser uma \u201cf\u00e1brica privada de inova\u00e7\u00e3o e desenvolvimento de softwares que tragam solu\u00e7\u00f5es que possam ajudar a acelerar as estrat\u00e9gias e a implementa\u00e7\u00e3o de medidas para o desenvolvimento do pa\u00eds\u201d.\u00a0 Segundo a dire\u00e7\u00e3o da operadora m\u00f3vel, este laborat\u00f3rio funcionar\u00e1 com forte participa\u00e7\u00e3o de jovens empreendedores e empreendedoras nacionais, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3602,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-3605","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"acf":{"introduction":"<b>Unitek Innovation Labs \u00e9 o novo programa criado pela operadora de telecomunica\u00e7\u00f5es nacional, Unitel T+, e tem como objetivo principal acelerar a incuba\u00e7\u00e3o de startups e a transforma\u00e7\u00e3o das ideias em modelos de neg\u00f3cios.<span class=\"Apple-converted-space\">\u00a0 <\/span>Foi apresentado na cidade de Santa Maria em outubro de 2022. <\/b>","key_takeaways":"","instagram-code":"","youtube-url":"","faqs":null,"enter_summary_here":""},"_links":{"self":[{"href":"https:\/\/cabowork.com\/pt-pt\/wp-json\/wp\/v2\/posts\/3605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cabowork.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cabowork.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cabowork.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cabowork.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=3605"}],"version-history":[{"count":5,"href":"https:\/\/cabowork.com\/pt-pt\/wp-json\/wp\/v2\/posts\/3605\/revisions"}],"predecessor-version":[{"id":3677,"href":"https:\/\/cabowork.com\/pt-pt\/wp-json\/wp\/v2\/posts\/3605\/revisions\/3677"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cabowork.com\/pt-pt\/wp-json\/wp\/v2\/media\/3602"}],"wp:attachment":[{"href":"https:\/\/cabowork.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=3605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cabowork.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=3605"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cabowork.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=3605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}